{"id":13588,"date":"2026-04-16T11:54:21","date_gmt":"2026-04-16T14:54:21","guid":{"rendered":"https:\/\/www.grupomotta.com\/?p=13588"},"modified":"2026-04-16T12:03:25","modified_gmt":"2026-04-16T15:03:25","slug":"2-seminario-internacional-avicola","status":"publish","type":"post","link":"https:\/\/www.grupomotta.com\/en\/2-seminario-internacional-avicola\/","title":{"rendered":"2\u00b0 Seminario Internacional Av\u00edcola"},"content":{"rendered":"<h1 data-pm-slice=\"1 1 []\">Visi\u00f3n, impulso y futuro: H\u00e9ctor Motta en el cierre del Seminario Av\u00edcola Internacional <\/p>\n<div class=\"hr-thin\"><\/div>\n<\/h1>\n<p data-pm-slice=\"1 1 []\"><strong>El Seminario Av\u00edcola Internacional, desarrollado entre Paran\u00e1 y Crespo, cerr\u00f3 con la participaci\u00f3n del Presidente de Grupo Motta, H\u00e9ctor Motta, quien volvi\u00f3 a posicionarse como una de las voces clave en la proyecci\u00f3n estrat\u00e9gica del sector. <\/strong><\/p>\n<p data-pm-slice=\"1 1 []\">Ante un auditorio integrado por productores, t\u00e9cnicos y referentes de la cadena, destac\u00f3 la necesidad de seguir elevando el nivel de la avicultura a partir de la innovaci\u00f3n, el conocimiento aplicado y una visi\u00f3n empresarial de largo plazo.<\/p>\n<p data-pm-slice=\"1 1 []\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-13589\" src=\"https:\/\/www.grupomotta.com\/wp-content\/uploads\/2026\/04\/670407980_1427710936067184_5003936769463740638_n.jpg\" alt=\"\" width=\"1200\" height=\"857\" srcset=\"https:\/\/www.grupomotta.com\/wp-content\/uploads\/2026\/04\/670407980_1427710936067184_5003936769463740638_n.jpg 1200w, https:\/\/www.grupomotta.com\/wp-content\/uploads\/2026\/04\/670407980_1427710936067184_5003936769463740638_n-300x214.jpg 300w, https:\/\/www.grupomotta.com\/wp-content\/uploads\/2026\/04\/670407980_1427710936067184_5003936769463740638_n-1024x731.jpg 1024w, https:\/\/www.grupomotta.com\/wp-content\/uploads\/2026\/04\/670407980_1427710936067184_5003936769463740638_n-768x548.jpg 768w, https:\/\/www.grupomotta.com\/wp-content\/uploads\/2026\/04\/670407980_1427710936067184_5003936769463740638_n-18x12.jpg 18w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/p>\n<p data-pm-slice=\"1 1 []\">En ese marco, puso especial \u00e9nfasis en el rol de AFIDEER como plataforma para impulsar el emprendedurismo y fortalecer la articulaci\u00f3n con el sistema acad\u00e9mico, promoviendo v\u00ednculos concretos con universidades de Entre R\u00edos y la Universidad de Salamanca. Un enfoque que consolida la formaci\u00f3n de nuevas generaciones con mirada global y anclaje territorial.<\/p>\n<p data-pm-slice=\"1 1 []\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-13590\" src=\"https:\/\/www.grupomotta.com\/wp-content\/uploads\/2026\/04\/671575786_1427709786067299_1151149614373173090_n.jpg\" alt=\"\" width=\"1200\" height=\"857\" srcset=\"https:\/\/www.grupomotta.com\/wp-content\/uploads\/2026\/04\/671575786_1427709786067299_1151149614373173090_n.jpg 1200w, https:\/\/www.grupomotta.com\/wp-content\/uploads\/2026\/04\/671575786_1427709786067299_1151149614373173090_n-300x214.jpg 300w, https:\/\/www.grupomotta.com\/wp-content\/uploads\/2026\/04\/671575786_1427709786067299_1151149614373173090_n-1024x731.jpg 1024w, https:\/\/www.grupomotta.com\/wp-content\/uploads\/2026\/04\/671575786_1427709786067299_1151149614373173090_n-768x548.jpg 768w, https:\/\/www.grupomotta.com\/wp-content\/uploads\/2026\/04\/671575786_1427709786067299_1151149614373173090_n-18x12.jpg 18w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/p>\n<p data-pm-slice=\"1 1 []\">El encuentro cont\u00f3 con el esponsoreo de <strong>Caba\u00f1a Av\u00edcola Feller, <\/strong>reafirmando su compromiso con el desarrollo del sector y su rol activo en la generaci\u00f3n de espacios que potencian el crecimiento de productores y empresas.<\/p>\n<p>Con un mensaje claro y consistente H\u00e9ctor Motta volvi\u00f3 a marcar el rumbo, expresando que el futuro de la avicultura se construye integrando experiencia, conocimiento, innovaci\u00f3n y sostenibilidad.<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-13591\" src=\"https:\/\/www.grupomotta.com\/wp-content\/uploads\/2026\/04\/whatsapp-image-2026-04-15-at-8.22.07-am-1.jpeg\" alt=\"\" width=\"1200\" height=\"675\" srcset=\"https:\/\/www.grupomotta.com\/wp-content\/uploads\/2026\/04\/whatsapp-image-2026-04-15-at-8.22.07-am-1.jpeg 1200w, https:\/\/www.grupomotta.com\/wp-content\/uploads\/2026\/04\/whatsapp-image-2026-04-15-at-8.22.07-am-1-300x169.jpeg 300w, https:\/\/www.grupomotta.com\/wp-content\/uploads\/2026\/04\/whatsapp-image-2026-04-15-at-8.22.07-am-1-1024x576.jpeg 1024w, https:\/\/www.grupomotta.com\/wp-content\/uploads\/2026\/04\/whatsapp-image-2026-04-15-at-8.22.07-am-1-768x432.jpeg 768w, https:\/\/www.grupomotta.com\/wp-content\/uploads\/2026\/04\/whatsapp-image-2026-04-15-at-8.22.07-am-1-18x10.jpeg 18w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/p>","protected":false},"excerpt":{"rendered":"<p>Visi\u00f3n, impulso y futuro: H\u00e9ctor Motta en el cierre del Seminario Av\u00edcola Internacional El Seminario Av\u00edcola Internacional, desarrollado entre Paran\u00e1 y Crespo, cerr\u00f3 con la participaci\u00f3n del Presidente de Grupo Motta, H\u00e9ctor Motta, quien volvi\u00f3 a posicionarse como una de las voces clave en la proyecci\u00f3n estrat\u00e9gica del sector. Ante un auditorio integrado por productores,&hellip;<\/p>","protected":false},"author":8,"featured_media":13597,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"yst_prominent_words":[233,921,698,898,639,106,99,503,922,45,580,924,228,581,920,919,834,923],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 05:27:21","action":"draft","terms":[],"taxonomy":"category"},"_links":{"self":[{"href":"https:\/\/www.grupomotta.com\/en\/wp-json\/wp\/v2\/posts\/13588"}],"collection":[{"href":"https:\/\/www.grupomotta.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.grupomotta.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.grupomotta.com\/en\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.grupomotta.com\/en\/wp-json\/wp\/v2\/comments?post=13588"}],"version-history":[{"count":1,"href":"https:\/\/www.grupomotta.com\/en\/wp-json\/wp\/v2\/posts\/13588\/revisions"}],"predecessor-version":[{"id":13592,"href":"https:\/\/www.grupomotta.com\/en\/wp-json\/wp\/v2\/posts\/13588\/revisions\/13592"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.grupomotta.com\/en\/wp-json\/wp\/v2\/media\/13597"}],"wp:attachment":[{"href":"https:\/\/www.grupomotta.com\/en\/wp-json\/wp\/v2\/media?parent=13588"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.grupomotta.com\/en\/wp-json\/wp\/v2\/categories?post=13588"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.grupomotta.com\/en\/wp-json\/wp\/v2\/tags?post=13588"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/www.grupomotta.com\/en\/wp-json\/wp\/v2\/yst_prominent_words?post=13588"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}